{"id":45659,"date":"2025-03-26T08:23:40","date_gmt":"2025-03-26T07:23:40","guid":{"rendered":"https:\/\/www.instabilelab.com\/?post_type=product&#038;p=45659"},"modified":"2025-03-26T08:23:40","modified_gmt":"2025-03-26T07:23:40","slug":"modern-wallpaper-with-lines-tamami-instabilelab","status":"publish","type":"product","link":"https:\/\/instabilelab.com\/en\/product\/modern-wallpaper-with-lines-tamami-instabilelab\/","title":{"rendered":"Tamami"},"featured_media":46670,"template":"","categoria-prodotto":[133],"catalogo":[1006],"colore":[845,847,857,864],"ambiente":[595],"tema":[634,645,817],"stile":[742,750,763,766],"class_list":["post-45659","product","type-product","status-publish","has-post-thumbnail","hentry","categoria-prodotto-wallcovering-wallpaper-instabilelab","catalogo-myway-en","colore-beige-en","colore-white","colore-gray","colore-black","ambiente-living-room","tema-geometric","tema-nature","tema-landscapes","stile-decorative","stile-elegant","stile-modern","stile-original"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Modern wallpaper with lines - Tamami Instabilelab<\/title>\n<meta name=\"description\" content=\"Modern wallpaper with geometric lines and references to landscapes for a perfect balance between contemporary design and nature.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/instabilelab.com\/en\/product\/modern-wallpaper-with-lines-tamami-instabilelab\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modern wallpaper with lines - Tamami Instabilelab\" \/>\n<meta property=\"og:description\" content=\"Modern wallpaper with geometric lines and references to landscapes for a perfect balance between contemporary design and nature.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/instabilelab.com\/en\/product\/modern-wallpaper-with-lines-tamami-instabilelab\/\" \/>\n<meta property=\"og:site_name\" content=\"Instabilelab\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/instabilelab\" \/>\n<meta property=\"og:image\" content=\"https:\/\/instabilelab.com\/wp-content\/uploads\/2025\/02\/Tamami-carta-da-parati-moderna-con-linee.-Catalogo-My-Way.-Instabilelab.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1190\" \/>\n\t<meta property=\"og:image:height\" content=\"1700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/instabilelab.com\\\/en\\\/product\\\/modern-wallpaper-with-lines-tamami-instabilelab\\\/\",\"url\":\"https:\\\/\\\/instabilelab.com\\\/en\\\/product\\\/modern-wallpaper-with-lines-tamami-instabilelab\\\/\",\"name\":\"Modern wallpaper with lines - Tamami Instabilelab\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/instabilelab.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/instabilelab.com\\\/en\\\/product\\\/modern-wallpaper-with-lines-tamami-instabilelab\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/instabilelab.com\\\/en\\\/product\\\/modern-wallpaper-with-lines-tamami-instabilelab\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/instabilelab.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Tamami-carta-da-parati-moderna-con-linee.-Catalogo-My-Way.-Instabilelab.jpg\",\"datePublished\":\"2025-03-26T07:23:40+00:00\",\"description\":\"Modern wallpaper with geometric lines and references to landscapes for a perfect balance between contemporary design and nature.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/instabilelab.com\\\/en\\\/product\\\/modern-wallpaper-with-lines-tamami-instabilelab\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/instabilelab.com\\\/en\\\/product\\\/modern-wallpaper-with-lines-tamami-instabilelab\\\/#primaryimage\",\"url\":\"https:\\\/\\\/instabilelab.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Tamami-carta-da-parati-moderna-con-linee.-Catalogo-My-Way.-Instabilelab.jpg\",\"contentUrl\":\"https:\\\/\\\/instabilelab.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Tamami-carta-da-parati-moderna-con-linee.-Catalogo-My-Way.-Instabilelab.jpg\",\"width\":1190,\"height\":1700},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/instabilelab.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/instabilelab.com\\\/en\\\/\",\"name\":\"Instabilelab\",\"description\":\"Interior Design\",\"alternateName\":\"Carta da Parati Tessili e Tappeti\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/instabilelab.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Modern wallpaper with lines - Tamami Instabilelab","description":"Modern wallpaper with geometric lines and references to landscapes for a perfect balance between contemporary design and nature.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/instabilelab.com\/en\/product\/modern-wallpaper-with-lines-tamami-instabilelab\/","og_locale":"en_US","og_type":"article","og_title":"Modern wallpaper with lines - Tamami Instabilelab","og_description":"Modern wallpaper with geometric lines and references to landscapes for a perfect balance between contemporary design and nature.","og_url":"https:\/\/instabilelab.com\/en\/product\/modern-wallpaper-with-lines-tamami-instabilelab\/","og_site_name":"Instabilelab","article_publisher":"https:\/\/www.facebook.com\/instabilelab","og_image":[{"width":1190,"height":1700,"url":"https:\/\/instabilelab.com\/wp-content\/uploads\/2025\/02\/Tamami-carta-da-parati-moderna-con-linee.-Catalogo-My-Way.-Instabilelab.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/instabilelab.com\/en\/product\/modern-wallpaper-with-lines-tamami-instabilelab\/","url":"https:\/\/instabilelab.com\/en\/product\/modern-wallpaper-with-lines-tamami-instabilelab\/","name":"Modern wallpaper with lines - Tamami Instabilelab","isPartOf":{"@id":"https:\/\/instabilelab.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/instabilelab.com\/en\/product\/modern-wallpaper-with-lines-tamami-instabilelab\/#primaryimage"},"image":{"@id":"https:\/\/instabilelab.com\/en\/product\/modern-wallpaper-with-lines-tamami-instabilelab\/#primaryimage"},"thumbnailUrl":"https:\/\/instabilelab.com\/wp-content\/uploads\/2025\/02\/Tamami-carta-da-parati-moderna-con-linee.-Catalogo-My-Way.-Instabilelab.jpg","datePublished":"2025-03-26T07:23:40+00:00","description":"Modern wallpaper with geometric lines and references to landscapes for a perfect balance between contemporary design and nature.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/instabilelab.com\/en\/product\/modern-wallpaper-with-lines-tamami-instabilelab\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/instabilelab.com\/en\/product\/modern-wallpaper-with-lines-tamami-instabilelab\/#primaryimage","url":"https:\/\/instabilelab.com\/wp-content\/uploads\/2025\/02\/Tamami-carta-da-parati-moderna-con-linee.-Catalogo-My-Way.-Instabilelab.jpg","contentUrl":"https:\/\/instabilelab.com\/wp-content\/uploads\/2025\/02\/Tamami-carta-da-parati-moderna-con-linee.-Catalogo-My-Way.-Instabilelab.jpg","width":1190,"height":1700},{"@type":"WebSite","@id":"https:\/\/instabilelab.com\/en\/#website","url":"https:\/\/instabilelab.com\/en\/","name":"Instabilelab","description":"Interior Design","alternateName":"Carta da Parati Tessili e Tappeti","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/instabilelab.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/instabilelab.com\/en\/wp-json\/wp\/v2\/product\/45659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instabilelab.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/instabilelab.com\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/instabilelab.com\/en\/wp-json\/wp\/v2\/product\/45659\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instabilelab.com\/en\/wp-json\/wp\/v2\/media\/46670"}],"wp:attachment":[{"href":"https:\/\/instabilelab.com\/en\/wp-json\/wp\/v2\/media?parent=45659"}],"wp:term":[{"taxonomy":"categoria-prodotto","embeddable":true,"href":"https:\/\/instabilelab.com\/en\/wp-json\/wp\/v2\/categoria-prodotto?post=45659"},{"taxonomy":"catalogo","embeddable":true,"href":"https:\/\/instabilelab.com\/en\/wp-json\/wp\/v2\/catalogo?post=45659"},{"taxonomy":"colore","embeddable":true,"href":"https:\/\/instabilelab.com\/en\/wp-json\/wp\/v2\/colore?post=45659"},{"taxonomy":"ambiente","embeddable":true,"href":"https:\/\/instabilelab.com\/en\/wp-json\/wp\/v2\/ambiente?post=45659"},{"taxonomy":"tema","embeddable":true,"href":"https:\/\/instabilelab.com\/en\/wp-json\/wp\/v2\/tema?post=45659"},{"taxonomy":"stile","embeddable":true,"href":"https:\/\/instabilelab.com\/en\/wp-json\/wp\/v2\/stile?post=45659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}